{"id":170,"count":2,"description":"","link":"https:\/\/freiheitskalender.ch\/it\/tag\/freiwilligkeit\/","name":"Freiwilligkeit","slug":"freiwilligkeit","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Freiwilligkeit Archive - Freiheitskalender<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freiheitskalender.ch\/it\/tag\/freiwilligkeit\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freiwilligkeit Archive - Freiheitskalender\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freiheitskalender.ch\/it\/tag\/freiwilligkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Freiheitskalender\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/tag\\\/freiwilligkeit\\\/\",\"url\":\"https:\\\/\\\/freiheitskalender.ch\\\/tag\\\/freiwilligkeit\\\/\",\"name\":\"Freiwilligkeit Archive - Freiheitskalender\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/#website\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/#website\",\"url\":\"https:\\\/\\\/freiheitskalender.ch\\\/\",\"name\":\"Freiheitskalender\",\"description\":\"Termine aus der Community\",\"publisher\":{\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freiheitskalender.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/#organization\",\"name\":\"Freiheitskalender\",\"url\":\"https:\\\/\\\/freiheitskalender.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/freiheitskalender.ch\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Freiheitskalender-Logo-flach_Logo_NEW_21.10.2025_DE_100PX.png\",\"contentUrl\":\"https:\\\/\\\/freiheitskalender.ch\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Freiheitskalender-Logo-flach_Logo_NEW_21.10.2025_DE_100PX.png\",\"width\":1000,\"height\":340,\"caption\":\"Freiheitskalender\"},\"image\":{\"@id\":\"https:\\\/\\\/freiheitskalender.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freiwilligkeit Archive - Freiheitskalender","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freiheitskalender.ch\/it\/tag\/freiwilligkeit\/","og_locale":"it_IT","og_type":"article","og_title":"Freiwilligkeit Archive - Freiheitskalender","og_url":"https:\/\/freiheitskalender.ch\/it\/tag\/freiwilligkeit\/","og_site_name":"Freiheitskalender","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/freiheitskalender.ch\/tag\/freiwilligkeit\/","url":"https:\/\/freiheitskalender.ch\/tag\/freiwilligkeit\/","name":"Freiwilligkeit Archive - Freiheitskalender","isPartOf":{"@id":"https:\/\/freiheitskalender.ch\/#website"},"inLanguage":"it-IT"},{"@type":"WebSite","@id":"https:\/\/freiheitskalender.ch\/#website","url":"https:\/\/freiheitskalender.ch\/","name":"Calendario della Libert\u00e0","description":"Termine aus der Community","publisher":{"@id":"https:\/\/freiheitskalender.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freiheitskalender.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/freiheitskalender.ch\/#organization","name":"Calendario della Libert\u00e0","url":"https:\/\/freiheitskalender.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/freiheitskalender.ch\/#\/schema\/logo\/image\/","url":"https:\/\/freiheitskalender.ch\/wp-content\/uploads\/2025\/10\/Freiheitskalender-Logo-flach_Logo_NEW_21.10.2025_DE_100PX.png","contentUrl":"https:\/\/freiheitskalender.ch\/wp-content\/uploads\/2025\/10\/Freiheitskalender-Logo-flach_Logo_NEW_21.10.2025_DE_100PX.png","width":1000,"height":340,"caption":"Freiheitskalender"},"image":{"@id":"https:\/\/freiheitskalender.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/freiheitskalender.ch\/it\/wp-json\/wp\/v2\/tags\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freiheitskalender.ch\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/freiheitskalender.ch\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/freiheitskalender.ch\/it\/wp-json\/wp\/v2\/posts?tags=170"},{"href":"https:\/\/freiheitskalender.ch\/it\/wp-json\/wp\/v2\/tribe_events?tags=170"},{"href":"https:\/\/freiheitskalender.ch\/it\/wp-json\/wp\/v2\/tec_calendar_embed?tags=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}